{"text_format":"1","workbook":"xlsx","n_sheets":6,"sheets":["(1)&(2)","(3) Export Activity Detail","FormData","RawData","Facility","AllProductData"],"not_rendered":{"charts":0,"images":2,"macros":1,"external_links":0,"defined_names":2,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"(1)&(2)","index":0,"n_rows":69,"n_cols":53,"rows_kept":69,"cut":false,"hidden":false,"merged":[[2,0,2,7],[5,44,5,49],[6,42,6,49],[7,40,7,49],[8,0,8,49],[9,0,9,49],[24,27,25,48],[10,0,11,49],[12,0,13,24],[12,25,13,49],[16,6,16,20],[18,18,18,19],[18,27,20,48],[20,18,20,19],[24,1,26,22],[31,27,32,48],[40,16,40,17],[45,8,45,20],[47,5,47,8],[47,16,47,17],[67,2,67,11],[67,14,67,24],[67,26,67,29],[36,8,36,20],[40,5,40,8],[51,12,51,13],[51,17,51,18],[53,8,53,20],[57,0,62,49],[49,7,49,20],[38,8,38,20]]}
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Raw Data"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Resubmission?",{"$f":"'(3) Export Activity Detail'!J31","v":"N"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Company Name",{"$f":"G17","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rpt Pd",{"$f":"CONCATENATE(S19,O19)","v":""}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rpt Date",{"$f":"CONCATENATE(K21,\"/\",O21,\"/\",S21)","v":"//"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Phone: (808) 587-3807",null,null,null,null,null,null,"ID No",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Email: dbedt.hseo.eiirp@hawaii.gov",null,null,null,null,null,null,null,null,"Info changed?"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"https://energy.hawaii.gov/eiirp ",null,null,null,null,null,null,null,null,null,null,"Distributor"]
["Form DBEDT-111",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Refiner"]
["MONTHLY PETROLEUM EXPORTS REPORT",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Facility Location",{"$f":"I37","v":0}]
["This Report is mandatory under chapter 486J, Hawaii Revised Statutes (\"HRS\").  Violations are subject to civil and criminal penalties pursuant to HRS § 486J-9 and other applicable laws or orders. CONFIDENTIAL PURSUANT TO APPLICABLE STATUTORY AUTHORITY (E.G., HRS § 486J-6) AND APPLICABLE PROTECTIVE ORDERS.",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Facility City",{"$f":"F41","v":" "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Facility State",{"$f":"M41","v":" "}]
["Part 1. Respondent Identification",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Part 2. Submission or Resubmission Information",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Facility Zip",{"$f":"Q41","v":" "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mailing Add same?",false]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mailing Add",{"$f":"I46","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mailing City",{"$f":"F48","v":0}]
[null,"COMPANY NAME:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mailing State",{"$f":"M48","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mailing Zip",{"$f":"Q48","v":0}]
[null,"REPORT PERIOD  (Month Ending):",null,null,null,null,null,null,null,null,"MONTH (##)",null,null,null,null,null,"YEAR",null,null,null,null,null,null,null,null,null,null,"A completed form must be received on or before the last day of the month following the end of the report month (e.g, July 2023 report period must be received on or before August 31, 2023).",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Contact Name",{"$f":"H50","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Phone ",{"$f":"CONCATENATE(I52,\"-\",K52,\"-\",M52,\"Ext\",R52)","v":"--Ext"}]
[null,"SUBMISSION DATE:",null,null,null,null,"MONTH (##)",null,null,null,null,null,"DAY",null,null,null,"YEAR",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Email",{"$f":"I54","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Comments",{"$f":"A58","v":0}]
[]
[]
[null,"If respondent contact information has changed since the previous report, please check box and fill out the form below. If more than one contact and/or facility information has changed, please provide additional changes in the comments section below.",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Please submit a separate report for each exporting facility. "]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Forms must be uploaded to ",null,null,null,null,null,null,"https://eiirp.hawaii.gov/"]
[]
[]
[null,null,null,"Doing business as a (check all that apply):",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"If you have any questions about the form after reading the PDF instructions, please contact HSEO at (808) 587-3807."]
[]
[]
[]
[]
[null,null,null,"Facility Name:"]
[]
[null,null,null,"Facility Location:",null,null,null,null,{"$f":"_xlfn.IFNA(VLOOKUP($I$37,Facility!$A$2:$F$35, 2, FALSE), \" \" )","v":" "}]
[]
[null,null,null,"City: ",null,{"$f":"_xlfn.IFNA(VLOOKUP($I$37,Facility!$A$2:$F$35, 3, FALSE), \" \" )","v":" "},null,null,null,null,"State: ",null,{"$f":"_xlfn.IFNA(VLOOKUP($I$37,Facility!$A$2:$F$35, 4, FALSE), \" \" )","v":" "},null,"   Zip:  ",null,{"$f":"_xlfn.IFNA(VLOOKUP($I$37,Facility!$A$2:$F$35, 5, FALSE), \" \" )","v":" "}]
[]
[]
[]
[]
[null,null,null,"Mailing Address:"]
[]
[null,null,null,"City: ",null,null,null,null,null,null,"State: ",null,null,null,"   Zip:  "]
[]
[null,null,null,"Contact Name: "]
[]
[null,null,null,"Phone Number: ",null,null,null,null,null,"­",null,"­",null,null,null,"   Ext.:"]
[]
[null,null,null,"Email address: "]
[]
[]
["COMMENTS: Please decribe any unusual aspect of the company's reporting month's operations and/or reason for resubmission."]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,"I certify under penalty of perjury (under section 486J-9b) that the information contained in this report is true, correct and complete to the best of my knowledge. I am authorized to file this report on behalf of the company."]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"CONCATENATE(K21,\"/\",O21,\"/\",S21)","v":"//"}]
[null,null,"Name",null,null,null,null,null,null,null,null,null,null,null,"Title",null,null,null,null,null,null,null,null,null,null,null,"Date"]

{"sheet":"(3) Export Activity Detail","index":1,"n_rows":82,"n_cols":31,"rows_kept":82,"cut":false,"hidden":false,"merged":[[28,0,28,8],[28,9,28,19],[29,9,29,19],[30,9,30,19],[35,1,35,12],[40,15,40,19],[41,15,41,19],[29,0,29,8],[30,0,30,8],[39,15,39,19],[58,1,58,12],[59,1,59,12],[71,1,71,12],[71,15,71,19],[74,1,74,12],[74,15,74,19],[55,15,55,19],[72,1,72,12],[20,9,20,19],[21,9,21,19],[22,9,22,19],[23,9,23,19],[24,9,24,19],[25,9,25,19],[26,9,26,19],[27,9,27,19],[20,0,20,8],[21,0,21,8],[22,0,22,8],[23,0,23,8],[24,0,24,8],[25,0,25,8],[26,0,26,8],[27,0,27,8],[68,27,68,31],[70,20,70,26],[70,27,70,31],[62,20,62,26],[63,20,63,26],[64,20,64,26],[65,20,65,26],[66,20,66,26],[79,12,79,16],[77,12,77,16],[63,15,63,19],[62,1,62,12],[63,1,63,12],[64,1,64,12],[65,1,65,12],[66,1,66,12],[68,1,68,12],[70,1,70,12],[70,15,70,19],[64,15,64,19],[65,15,65,19],[66,15,66,19],[33,0,34,0],[41,20,41,26],[41,27,41,31],[57,20,57,26],[54,20,54,26],[54,27,54,31],[55,20,55,26],[52,27,52,31],[53,20,53,26],[53,27,53,31],[42,20,42,26],[42,27,42,31],[48,27,48,31],[49,20,49,26],[49,27,49,31],[50,20,50,26],[50,27,50,31],[45,27,45,31],[46,20,46,26],[46,27,46,31],[47,20,47,26],[47,27,47,31],[53,15,53,19],[54,15,54,19],[33,20,34,26],[33,27,34,31],[44,15,44,19],[51,15,51,19],[49,15,49,19],[50,15,50,19],[16,0,17,31],[56,1,56,12],[57,1,57,12],[42,1,42,12],[43,1,43,12],[44,1,44,12],[37,20,37,26],[37,27,37,31],[38,20,38,26],[38,27,38,31],[39,20,39,26],[39,27,39,31],[35,20,35,26],[35,27,35,31],[36,20,36,26],[36,27,36,31],[51,27,51,31],[52,20,52,26],[33,14,34,14],[38,15,38,19],[38,1,38,12],[39,1,39,12],[33,15,34,19],[47,1,47,12],[48,1,48,12],[49,1,49,12],[50,1,50,12],[40,1,40,12],[41,1,41,12],[36,1,36,12],[37,1,37,12],[33,1,34,12],[55,1,55,12],[57,27,57,31],[58,20,58,26],[58,27,58,31],[68,15,68,19],[46,15,46,19],[47,15,47,19],[48,15,48,19],[56,15,56,19],[62,15,62,19],[59,15,59,19],[58,15,58,19],[52,15,52,19],[61,15,61,19],[51,1,51,12],[56,27,56,31],[55,27,55,31],[56,20,56,26],[51,20,51,26],[62,27,62,31],[63,27,63,31],[64,27,64,31],[65,27,65,31],[66,27,66,31],[46,1,46,12],[45,15,45,19],[71,20,71,26],[71,27,71,31],[72,15,72,19],[72,20,72,26],[72,27,72,31],[40,27,40,31],[43,27,43,31],[42,15,42,19],[61,1,61,12],[61,20,61,26],[61,27,61,31],[44,27,44,31],[43,15,43,19],[43,20,43,26],[57,15,57,19],[45,20,45,26],[48,20,48,26],[59,20,59,26],[59,27,59,31],[52,1,52,12],[53,1,53,12],[54,1,54,12],[67,1,67,12],[67,15,67,19],[67,20,67,26],[67,27,67,31],[10,26,10,31],[11,24,11,31],[12,22,12,31],[74,20,74,26],[74,27,74,31],[60,1,60,12],[35,15,35,19],[36,15,36,19],[37,15,37,19],[60,15,60,19],[60,27,60,31],[60,20,60,26],[68,20,68,26],[73,1,73,12],[73,15,73,19],[73,20,73,26],[73,27,73,31],[40,20,40,26],[44,20,44,26],[45,1,45,12]]}
["Part 3. Export Activity Detail"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Phone: (808) 587-3807"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Email: dbedt.hseo.eiirp@hawaii.gov"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"https://energy.hawaii.gov/eiirp"]
["Form DBEDT-111"]
["MONTHLY PETROLEUM EXPORTS REPORT"]
[]
["This Report is mandatory under chapter 486J, Hawaii Revised Statutes (\"HRS\").  Violations are subject to civil and criminal penalties pursuant to HRS § 486J-9 and other applicable laws or orders. CONFIDENTIAL PURSUANT TO APPLICABLE STATUTORY AUTHORITY (E.G., HRS § 486J-6) AND APPLICABLE PROTECTIVE ORDERS."]
[]
[]
[]
["Company Name",null,null,null,null,null,null,null,null,{"$f":"IF('(1)&(2)'!G17=0,\" \",'(1)&(2)'!G17)","v":" "}]
["Company Short Code",null,null,null,null,null,null,null,null,{"$f":"_xlfn.IFNA(INDEX(Facility!$A$38:$B$61, MATCH(J21,Facility!A38:A61,0), 2), \" \")","v":" "}]
["Company Code",null,null,null,null,null,null,null,null,{"$f":"_xlfn.IFNA(INDEX(Facility!$A$38:$C$61, MATCH(J21,Facility!A38:A61,0), 3), \"\")","v":""}]
["Form Code",null,null,null,null,null,null,null,null,{"$f":"IF(OR(J23=\"\",J25=\"\",J27=\"\",J30=\"\"),\"\",_xlfn.IFNA(_xlfn.CONCAT(J27,\"-\",J23,\"-\",_xlfn.IFNA(VLOOKUP('(3) Export Activity Detail'!$J$25,Facility!$A$2:$H$35, 8, FALSE), \"000\" ),\"-\",J30,\"-111\"), \"\"))","v":""}]
["Facility Name",null,null,null,null,null,null,null,null,{"$f":"IF('(1)&(2)'!I37=0,\"\",'(1)&(2)'!I37)","v":""}]
["Island",null,null,null,null,null,null,null,null,{"$f":"_xlfn.IFNA(VLOOKUP('(1)&(2)'!I37,Facility!$A$2:$F$35, 6, FALSE), \" \" )","v":" "}]
["Island Code",null,null,null,null,null,null,null,null,{"$f":"_xlfn.IFNA(INDEX(Facility!$A$65:$B$72, MATCH(J26,Facility!B65:B72,0), 1), \"\")","v":""}]
["Report Date",null,null,null,null,null,null,null,null,{"$f":"CONCATENATE('(1)&(2)'!K21,\"/\",'(1)&(2)'!O21,\"/\",'(1)&(2)'!S21)","v":"//"}]
["Report Period (Month Ending)",null,null,null,null,null,null,null,null,{"$f":"CONCATENATE('(1)&(2)'!O19,\"/\",'(1)&(2)'!S19)","v":"/"}]
["Report Period",null,null,null,null,null,null,null,null,{"$f":"_xlfn.CONCAT('(1)&(2)'!S19:T19,'(1)&(2)'!O19)","v":""}]
["Resubmission (Y/N)",null,null,null,null,null,null,null,null,{"$f":"IF(Facility!B75=TRUE,\"Y\",\"N\")","v":"N"}]
[]
[]
["Line No.","Product Description",null,null,null,null,null,null,null,null,null,null,null,null,"Product No.","Port of Exit",null,null,null,null,"Destination: State or Country",null,null,null,null,null,null,"Volume of Export (Barrels)"]
[]
[1,"Crude Oil",null,null,null,null,null,null,null,null,null,null,null,null,"001"]
[2,"Unleaded Gasoline Regular (no ethanol finished)",null,null,null,null,null,null,null,null,null,null,null,null,"002"]
[3,"Unleaded Gasoline Midgrade (no ethanol finished)",null,null,null,null,null,null,null,null,null,null,null,null,"003"]
[4,"Unleaded Gasoline Premium (no ethanol finished)",null,null,null,null,null,null,null,null,null,null,null,null,"004"]
[5,"Gasoline (E10) Regular",null,null,null,null,null,null,null,null,null,null,null,null,"005"]
[6,"Gasoline (E10) Midgrade",null,null,null,null,null,null,null,null,null,null,null,null,"006"]
[7,"Gasoline (E10) Premium",null,null,null,null,null,null,null,null,null,null,null,null,"007"]
[8,"HIBOB Regular",null,null,null,null,null,null,null,null,null,null,null,null,"008"]
[9,"HIBOB Premium",null,null,null,null,null,null,null,null,null,null,null,null,"009"]
[10,"Aviation",null,null,null,null,null,null,null,null,null,null,null,null,"010"]
[11,"Jet Kerosene, Non-bonded",null,null,null,null,null,null,null,null,null,null,null,null,"011"]
[12,"Jet Kerosene, Bonded",null,null,null,null,null,null,null,null,null,null,null,null,"012"]
[13,"Military Jet Fuel (JP5 and JP8)",null,null,null,null,null,null,null,null,null,null,null,null,"013"]
[14,"No. 2 Diesel Sulfur <= 15 ppm",null,null,null,null,null,null,null,null,null,null,null,null,"015"]
[15,"No. 2 Diesel 15 ppm < Sulfur <= 500 ppm",null,null,null,null,null,null,null,null,null,null,null,null,"016"]
[16,"No. 2 Diesel Sulfur > 500",null,null,null,null,null,null,null,null,null,null,null,null,"017"]
[17,"No. 2 Fuel Oil",null,null,null,null,null,null,null,null,null,null,null,null,"018"]
[18,"Residual Fuel Oil <= 1%",null,null,null,null,null,null,null,null,null,null,null,null,"021"]
[19,"Residual Fuel Oil > 1%",null,null,null,null,null,null,null,null,null,null,null,null,"022"]
[20,"Vacuum Gas Oil",null,null,null,null,null,null,null,null,null,null,null,null,"024"]
[21,"Intermediate Fuel Oil",null,null,null,null,null,null,null,null,null,null,null,null,"025"]
[22,"Asphalt",null,null,null,null,null,null,null,null,null,null,null,null,"029"]
[23,"Propane HD-5 (Consumer)",null,null,null,null,null,null,null,null,null,null,null,null,"030"]
[24,"Ethanol",null,null,null,null,null,null,null,null,null,null,null,null,"034"]
[25,"Biodiesel >95%",null,null,null,null,null,null,null,null,null,null,null,null,"036"]
[26,"Biodiesel <30%",null,null,null,null,null,null,null,null,null,null,null,null,"037"]
[27,"Synthetic Natural Gas",null,null,null,null,null,null,null,null,null,null,null,1,"038"]
[28,"Synthetic Natural Gas Feedstock",null,null,null,null,null,null,null,null,null,null,null,1,"039"]
[29,"Alkylate",null,null,null,null,null,null,null,null,null,null,null,1,"040"]
[30,"Reformate",null,null,null,null,null,null,null,null,null,null,null,1,"041"]
[31,"Motor Gasoline Blend Components",null,null,null,null,null,null,null,null,null,null,null,1,"048"]
[32,"Naphtha",null,null,null,null,null,null,null,null,null,null,null,1,"049"]
[33,"Biodiesel Feedstock",null,null,null,null,null,null,null,null,null,null,null,null,"054"]
[34,"Unfinished Oil (all other)",null,null,null,null,null,null,null,null,null,null,null,1,"058"]
[35,"OTHER (Not listed above): Specify below"]
[36,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(A71>\" \",\"101\",\" \")","v":" "}," "]
[37,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[38,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[39,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[40,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[]
[]
[null,"TOTAL NUMBER OF PRODUCTS REPORTED",null,null,null,null,null,null,null,null,null,null,{"$f":"IF(COUNTIF(AB36:AB69,\">0\")=0,0,COUNTIF(AB36:AB69,\">0\"))+IF(COUNTIF(AB71:AB75,\">0\")=0,0,COUNTIF(AB71:AB75,\">0\"))","v":0}]
[]
[null,"TOTAL BARRELS REPORTED",null,null,null,null,null,null,null,null,null,null,{"$f":"SUM(AB36:AF75)","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Form code: ",null,null,{"$f":"J24","v":""},null,null,null,null,null,null,null,"DBEDT-111"]

{"sheet":"FormData","index":2,"n_rows":2,"n_cols":15,"rows_kept":2,"cut":false,"hidden":true,"merged":[]}
["form_code","dbedt","company_code","facility_code","island_code","report_date","report_period","report_period_month","report_period_year","resubmission","total_products_reported","total_barrels_reported","total_receipts","total_distribution","total_inventory"]
[{"$f":"'(3) Export Activity Detail'!J24","v":""},111,{"$f":"'(3) Export Activity Detail'!J23","v":""},{"$f":"_xlfn.IFNA(VLOOKUP('(3) Export Activity Detail'!$J$25,Facility!$A$2:$H$34,8, FALSE), \"\" )","v":""},{"$f":"'(3) Export Activity Detail'!J27","v":""},{"$f":"'(3) Export Activity Detail'!J28","v":"//"},{"$f":"'(3) Export Activity Detail'!J30","v":""},{"$f":"'(1)&(2)'!O19","v":0},{"$f":"'(1)&(2)'!S19","v":0},{"$f":"Facility!B75","v":false},{"$f":"'(3) Export Activity Detail'!M78","v":0},{"$f":"'(3) Export Activity Detail'!M80","v":0}]

{"sheet":"RawData","index":3,"n_rows":2,"n_cols":7,"rows_kept":2,"cut":false,"hidden":true,"merged":[]}
["form_code","product","product_code","destination","volume_export","port_exit","port_code"]
[{"$f":"_xlfn._xlws.SORT(_xlfn.UNIQUE(AllProductData!A2:G39,FALSE,FALSE),1,-1,FALSE)","v":""},"","","","","",""]

{"sheet":"Facility","index":4,"n_rows":335,"n_cols":8,"rows_kept":335,"cut":false,"hidden":true,"merged":[]}
["Facility Name","Facility Street Address","City","State","Zip","Island","Facility Code","Code"]
["Aloha Hilo Terminal","999 Kalanianaole Avenue","Hilo","HI","96720","Hawaii","TM_013","001"]
["Aloha Hilo Terminal 2","661 Kalanianaole Avenue","Hilo","HI","96720","Hawaii","TM_014","002"]
["Aloha Honolulu Terminal","789 North Nimitz Highway","Honolulu","HI","96817","O'ahu","TM_006","003"]
["Aloha Kahului Terminal","60 Hobron Avenue","Kahului","HI","96732","Maui","TM_015","004"]
["Aloha Nawiliwili Terminal","3145 Waapa Road","Lihue","HI","96766","Kaua'i","TM_016","005"]
["Aloha TFM Kalaeloa Terminal","91-119 Hanua Street","Kapolei","HI","96707","O'ahu","TM_010","006"]
["Hawaii Gas Barbers Point","91-571 Malakole St ","Kapolei","HI","96707","O'ahu","TM_011","007"]
["Hawaii Gas Hilo Base Yard","945 Kalanianaole Ave","Hilo","HI","96720","Hawaii","TM_017","008"]
["Hawaii Gas Kauai Base Yard","3000 Waapa Road","Lihue","HI","96766","Kaua'i","TM_018","009"]
["Hawaii Gas Kona","74-5564 Kaiwi Street","Kailua","HI","96740","Hawaii","TM_019","010"]
["Hawaii Gas Lanai","9th Street","Lanai City","HI","96763","Lana'i","TM_020","011"]
["Hawaii Gas Maui Base Yard","20 Hobron Avenue","Kahului","HI","96732","Maui","TM_021","012"]
["Hawaii Gas Molokai","Ulili Street","Kaunakakai","HI","96748","Moloka'i","TM_022","013"]
["Hawaii Petroleum Kona Cardlock","74-5558 B Kaiwi Street","Kailua-Kona","HI","96740","Hawaii","TM_023","014"]
["HFFC Airport","3201 Aolele Street","Honolulu","HI","96819","O'ahu","TM_001","015"]
["HFFC Sand Island ","50 Sand Island Access Road","Honolulu","HI","96819","O'ahu","TM_002","016"]
["IES Hilo","666 Kalanianaole Ave","Hilo","HI","96720","Hawaii","TM_024","017"]
["IES Honolulu","777 NI Nimitz Highway","Honolulu","HI","96817","O'ahu","TM_004","018"]
["IES Kahului","100 Hobron Ave","Kahului","HI","96732","Maui","TM_025","019"]
["IES Port Allen","260 Akaula St","Eleele","HI","96705","Kaua'i","TM_026","020"]
["Lanai Oil Terminal","Kaumalapau Highway","Lanai City","HI","96763","Lana'i","TM_028","022"]
["MidPac Petroleum Kawaihae Terminal","61-3651 Kawaihae Road","Kamuela","HI","96743","Hawaii","TM_029","023"]
["Pacific Biodiesel Terminal 1","1003 Makepono Street","Honolulu","HI","96819","O'ahu","TM_008","024"]
["Pacific Biodiesel Terminal 2","","Honolulu","HI",96819,"O'ahu","TM_035","025"]
["Pacific Biodiesel Terminal 3","40 Hobron Avenue","Kahului","HI","96732","Maui","TM_030","026"]
["Pacific Biodiesel Terminal 4","16-240 Mikahala Street","Keaau","HI","96749","Hawaii","TM_031","027"]
["Par Hilo","607 Kalanianaole Street","Hilo","HI","96720","Hawaii","TM_032","028"]
["Par Lihue","3651 Ahukini Road","Lihue","HI","96766","Kaua'i","TM_033","029"]
["Par Maui","140 A Hobron Avenue","Kahului","HI","96732","Maui","TM_034","030"]
["Par Mauka Terminal","#10 Wharf Rd/Beach Place","Kaunakakai","HI","96748","Moloka'i","TM_027","021"]
["Par Refinery-East","91-325 Komohana Street","Kapolei","HI","96707","O'ahu","RF_001","031"]
["Par Refinery-West","91-480 Malakole St","Kapolei","HI","96707","O'ahu","RF_002","032"]
["Par Sand Island","2 Sand Island Access Road","Honolulu","HI","96819","O'ahu","TM_007","033"]
[" "]
[]
["Company Name","Company Short Name","Company Code"]
["Aloha Petroleum Ltd","Aloha",10002]
["B&E Petroleum","BE",10001]
["BIG ISLAND ENERGY CO., LLC dba AKANA PETROLEUM","BIEnergy/Akana",70001]
["Big Island Biodiesel","BigIslBio",70002]
["Chevron U.S.A. Inc.","Chevron",10012]
["GARLOW PETROLEUM INC.","Garlow",10004]
["Hawaiian Electric Co., Inc.","HECO",10008]
["Hawaii Fueling Facilities Corporation","HFFC",10003]
["Hawaii Petroleum","HIPetro",80001]
["Island Energy Services","IESD",10012]
["Island Petroleum Inc.","Island",50001]
["Kauai Petroleum Co. LTD","KIPetro",20001]
["LANAI OIL COMPANY, INC.","LanaiOil",60001]
["MAUI OIL COMPANY, INC.","MauiOil",30003]
["Maui Electric Company, Ltd.","MECO",30002]
["Mid Pac Petroleum LLC","MidPac",10005]
["Maui Petroleum","MIPetro",30001]
["OAHU PETROLEUM, INC.","OahuPetro",10009]
["Pacific Biodiesel Inc","PacBio",10006]
["Par Pacific","PAR",10013]
["Senter Petroleum Inc.","Senter",20002]
["Shell Oil Products, US","Shell",10007]
["Tesoro Hawaii Corporation ","Tesoro",10011]
["THE GAS COMPANY, LLC","TGC",10010]
[]
[]
["Zone","Region"]
["1","O'ahu"]
["2","Kaua'i"]
["3","Maui"]
["4"]
["5","Moloka'i"]
["6","Lana'i"]
["7","Hawaii"]
["8"]
[]
[]
["Resubmission?",false]
[]
[]
["Ports","Zone","Code","Full Name","Asset_ID"]
["Kalaeloa Barbers Point","1","BAR","Kalaeloa Barbers Point Harbor, Oahu","PT_001"]
["Hilo","7","HIL","Hilo Harbor, Hawaii","PT_005"]
["Honolulu","1","HNL","Honolulu Harbor, Oahu","PT_004"]
["Kahului","3","KAH","Kahului Harbor, Maui","PT_006"]
["Kaunakakai","5","KAK","Kaunakakai Harbor, Molokai","PT_008"]
["Kaumalapau","6","KAU","Kaumalapau Harbor, Lanai","PT_007"]
["Kawaihae","8","KAW","Kawaihae Harbor, Hawaii","PT_009"]
["Kewalo Basin","1","KWB","Kewalo Basin, Oahu","PT_010"]
["Nawiliwili","2","NAW","Nawiliwili Harbor, Kauai","PT_011"]
["Port Allen","2","PTA","Port Allen Harbor, Kauai","PT_012"]
[]
[]
["Destinations"]
["Afghanistan"]
["Albania"]
["Algeria"]
["Andorra"]
["Angola"]
["Antigua and Barbuda"]
["Argentina"]
["Armenia"]
["Austria"]
["Azerbaijan"]
["Bahrain"]
["Bangladesh"]
["Barbados"]
["Belarus"]
["Belgium"]
["Belize"]
["Benin"]
["Bhutan"]
["Bolivia"]
["Bosnia and Herzegovina"]
["Botswana"]
["Brazil"]
["Brunei"]
["Bulgaria"]
["Burkina Faso"]
["Burundi"]
["Cabo Verde"]
["Cambodia"]
["Cameroon"]
["Canada"]
["Central African Republic"]
["Chad"]
["Channel Islands"]
["Chile"]
["China"]
["Colombia"]
["Comoros"]
["Congo"]
["Costa Rica"]
["CÃ´te d'Ivoire"]
["Croatia"]
["Cuba"]
["Cyprus"]
["Czech Republic"]
["Denmark"]
["Djibouti"]
["Dominica"]
["Dominican Republic"]
["DR Congo"]
["Ecuador"]
["Egypt"]
["El Salvador"]
["Equatorial Guinea"]
["Eritrea"]
["Estonia"]
["Eswatini"]
["Ethiopia"]
["Faeroe Islands"]
["Finland"]
["France"]
["French Guiana"]
["Gabon"]
["Gambia"]
["Georgia"]
["Germany"]
["Ghana"]
["Gibraltar"]
["Greece"]
["Grenada"]
["Guatemala"]
["Guinea"]
["Guinea-Bissau"]
["Guyana"]
["Haiti"]
["Holy See"]
["Honduras"]
["Hong Kong"]
["Hungary"]
["Iceland"]
["India"]
["Indonesia"]
["Iran"]
["Iraq"]
["Ireland"]
["Isle of Man"]
["Israel"]
["Italy"]
["Jamaica"]
["Japan"]
["Jordan"]
["Kazakhstan"]
["Kenya"]
["Kuwait"]
["Kyrgyzstan"]
["Laos"]
["Latvia"]
["Lebanon"]
["Lesotho"]
["Liberia"]
["Libya"]
["Liechtenstein"]
["Lithuania"]
["Luxembourg"]
["Macao"]
["Madagascar"]
["Malawi"]
["Malaysia"]
["Maldives"]
["Mali"]
["Malta"]
["Mauritania"]
["Mauritius"]
["Mayotte"]
["Mexico"]
["Moldova"]
["Monaco"]
["Mongolia"]
["Montenegro"]
["Morocco"]
["Mozambique"]
["Myanmar"]
["Namibia"]
["Nepal"]
["Netherlands"]
["Nicaragua"]
["Niger"]
["Nigeria"]
["North Korea"]
["North Macedonia"]
["Norway"]
["Oman"]
["Pakistan"]
["Panama"]
["Paraguay"]
["Peru"]
["Philippines"]
["Poland"]
["Portugal"]
["Qatar"]
["RÃ©union"]
["Romania"]
["Russia"]
["Rwanda"]
["Saint Helena"]
["Saint Kitts and Nevis"]
["Saint Lucia"]
["Saint Vincent and the Grenadines"]
["San Marino"]
["Sao Tome & Principe"]
["Saudi Arabia"]
["Senegal"]
["Serbia"]
["Seychelles"]
["Sierra Leone"]
["Singapore"]
["Slovakia"]
["Slovenia"]
["Somalia"]
["South Africa"]
["South Korea"]
["South Sudan"]
["Spain"]
["Sri Lanka"]
["State of Palestine"]
["Sudan"]
["Suriname"]
["Sweden"]
["Switzerland"]
["Syria"]
["Taiwan"]
["Tajikistan"]
["Tanzania"]
["Thailand"]
["The Bahamas"]
["Timor-Leste"]
["Togo"]
["Trinidad and Tobago"]
["Tunisia"]
["Turkey"]
["Turkmenistan"]
["Uganda"]
["Ukraine"]
["United Arab Emirates"]
["United Kingdom"]
["United States"]
["Uruguay"]
["Uzbekistan"]
["Venezuela"]
["Vietnam"]
["Western Sahara"]
["Yemen"]
["Zambia"]
["Zimbabwe"]
["Alabama"]
["Alaska"]
["Arizona"]
["Arkansas"]
["California"]
["Colorado"]
["Connecticut"]
["Delaware"]
["District of Columbia"]
["Florida"]
["Georgia"]
["Hawaii"]
["Idaho"]
["Illinois"]
["Indiana"]
["Iowa"]
["Kansas"]
["Kentucky"]
["Louisiana"]
["Maine"]
["Maryland"]
["Massachusetts"]
["Michigan"]
["Minnesota"]
["Mississippi"]
["Missouri"]
["Montana"]
["Nebraska"]
["Nevada"]
["New Hampshire"]
["New Jersey"]
["New Mexico"]
["New York"]
["North Carolina"]
["North Dakota"]
["Ohio"]
["Oklahoma"]
["Oregon"]
["Pennsylvania"]
["Rhode Island"]
["South Carolina"]
["South Dakota"]
["Tennessee"]
["Texas"]
["Utah"]
["Vermont"]
["Virginia"]
["Washington"]
["West Virginia"]
["Wisconsin"]
["Wyoming"]

{"sheet":"AllProductData","index":5,"n_rows":39,"n_cols":7,"rows_kept":39,"cut":false,"hidden":true,"merged":[]}
["form_code","product","product_code","destination","volume_export","port_exit","port_code"]
[{"$f":"IF(E2=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E2=\"\",\"\",'(3) Export Activity Detail'!B36)","v":""},{"$f":"IF(E2=\"\",\"\",'(3) Export Activity Detail'!O36)","v":""},{"$f":"IF(E2=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U36),\"\",'(3) Export Activity Detail'!U36))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB36),\"\",'(3) Export Activity Detail'!AB36)","v":""},{"$f":"IF(E2=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P36),\"\",LOOKUP('(3) Export Activity Detail'!P36,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E2=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P36),\"\",LOOKUP('(3) Export Activity Detail'!P36,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E3=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E3=\"\",\"\",'(3) Export Activity Detail'!B37)","v":""},{"$f":"IF(E3=\"\",\"\",'(3) Export Activity Detail'!O37)","v":""},{"$f":"IF(E3=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U37),\"\",'(3) Export Activity Detail'!U37))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB37),\"\",'(3) Export Activity Detail'!AB37)","v":""},{"$f":"IF(E3=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P37),\"\",LOOKUP('(3) Export Activity Detail'!P37,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E3=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P37),\"\",LOOKUP('(3) Export Activity Detail'!P37,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E4=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E4=\"\",\"\",'(3) Export Activity Detail'!B38)","v":""},{"$f":"IF(E4=\"\",\"\",'(3) Export Activity Detail'!O38)","v":""},{"$f":"IF(E4=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U38),\"\",'(3) Export Activity Detail'!U38))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB38),\"\",'(3) Export Activity Detail'!AB38)","v":""},{"$f":"IF(E4=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P38),\"\",LOOKUP('(3) Export Activity Detail'!P38,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E4=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P38),\"\",LOOKUP('(3) Export Activity Detail'!P38,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E5=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E5=\"\",\"\",'(3) Export Activity Detail'!B39)","v":""},{"$f":"IF(E5=\"\",\"\",'(3) Export Activity Detail'!O39)","v":""},{"$f":"IF(E5=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U39),\"\",'(3) Export Activity Detail'!U39))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB39),\"\",'(3) Export Activity Detail'!AB39)","v":""},{"$f":"IF(E5=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P39),\"\",LOOKUP('(3) Export Activity Detail'!P39,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E5=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P39),\"\",LOOKUP('(3) Export Activity Detail'!P39,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E6=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E6=\"\",\"\",'(3) Export Activity Detail'!B40)","v":""},{"$f":"IF(E6=\"\",\"\",'(3) Export Activity Detail'!O40)","v":""},{"$f":"IF(E6=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U40),\"\",'(3) Export Activity Detail'!U40))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB40),\"\",'(3) Export Activity Detail'!AB40)","v":""},{"$f":"IF(E6=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P40),\"\",LOOKUP('(3) Export Activity Detail'!P40,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E6=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P40),\"\",LOOKUP('(3) Export Activity Detail'!P40,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E7=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E7=\"\",\"\",'(3) Export Activity Detail'!B41)","v":""},{"$f":"IF(E7=\"\",\"\",'(3) Export Activity Detail'!O41)","v":""},{"$f":"IF(E7=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U41),\"\",'(3) Export Activity Detail'!U41))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB41),\"\",'(3) Export Activity Detail'!AB41)","v":""},{"$f":"IF(E7=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P41),\"\",LOOKUP('(3) Export Activity Detail'!P41,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E7=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P41),\"\",LOOKUP('(3) Export Activity Detail'!P41,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E8=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E8=\"\",\"\",'(3) Export Activity Detail'!B42)","v":""},{"$f":"IF(E8=\"\",\"\",'(3) Export Activity Detail'!O42)","v":""},{"$f":"IF(E8=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U42),\"\",'(3) Export Activity Detail'!U42))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB42),\"\",'(3) Export Activity Detail'!AB42)","v":""},{"$f":"IF(E8=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P42),\"\",LOOKUP('(3) Export Activity Detail'!P42,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E8=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P42),\"\",LOOKUP('(3) Export Activity Detail'!P42,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E9=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E9=\"\",\"\",'(3) Export Activity Detail'!B43)","v":""},{"$f":"IF(E9=\"\",\"\",'(3) Export Activity Detail'!O43)","v":""},{"$f":"IF(E9=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U43),\"\",'(3) Export Activity Detail'!U43))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB43),\"\",'(3) Export Activity Detail'!AB43)","v":""},{"$f":"IF(E9=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P43),\"\",LOOKUP('(3) Export Activity Detail'!P43,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E9=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P43),\"\",LOOKUP('(3) Export Activity Detail'!P43,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E10=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E10=\"\",\"\",'(3) Export Activity Detail'!B44)","v":""},{"$f":"IF(E10=\"\",\"\",'(3) Export Activity Detail'!O44)","v":""},{"$f":"IF(E10=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U44),\"\",'(3) Export Activity Detail'!U44))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB44),\"\",'(3) Export Activity Detail'!AB44)","v":""},{"$f":"IF(E10=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P44),\"\",LOOKUP('(3) Export Activity Detail'!P44,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E10=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P44),\"\",LOOKUP('(3) Export Activity Detail'!P44,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E11=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E11=\"\",\"\",'(3) Export Activity Detail'!B45)","v":""},{"$f":"IF(E11=\"\",\"\",'(3) Export Activity Detail'!O45)","v":""},{"$f":"IF(E11=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U45),\"\",'(3) Export Activity Detail'!U45))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB45),\"\",'(3) Export Activity Detail'!AB45)","v":""},{"$f":"IF(E11=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P45),\"\",LOOKUP('(3) Export Activity Detail'!P45,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E11=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P45),\"\",LOOKUP('(3) Export Activity Detail'!P45,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E12=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E12=\"\",\"\",'(3) Export Activity Detail'!B46)","v":""},{"$f":"IF(E12=\"\",\"\",'(3) Export Activity Detail'!O46)","v":""},{"$f":"IF(E12=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U46),\"\",'(3) Export Activity Detail'!U46))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB46),\"\",'(3) Export Activity Detail'!AB46)","v":""},{"$f":"IF(E12=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P46),\"\",LOOKUP('(3) Export Activity Detail'!P46,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E12=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P46),\"\",LOOKUP('(3) Export Activity Detail'!P46,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E13=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E13=\"\",\"\",'(3) Export Activity Detail'!B47)","v":""},{"$f":"IF(E13=\"\",\"\",'(3) Export Activity Detail'!O47)","v":""},{"$f":"IF(E13=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U47),\"\",'(3) Export Activity Detail'!U47))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB47),\"\",'(3) Export Activity Detail'!AB47)","v":""},{"$f":"IF(E13=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P47),\"\",LOOKUP('(3) Export Activity Detail'!P47,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E13=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P47),\"\",LOOKUP('(3) Export Activity Detail'!P47,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E14=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E14=\"\",\"\",'(3) Export Activity Detail'!B48)","v":""},{"$f":"IF(E14=\"\",\"\",'(3) Export Activity Detail'!O48)","v":""},{"$f":"IF(E14=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U48),\"\",'(3) Export Activity Detail'!U48))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB48),\"\",'(3) Export Activity Detail'!AB48)","v":""},{"$f":"IF(E14=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P48),\"\",LOOKUP('(3) Export Activity Detail'!P48,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E14=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P48),\"\",LOOKUP('(3) Export Activity Detail'!P48,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E15=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E15=\"\",\"\",'(3) Export Activity Detail'!B49)","v":""},{"$f":"IF(E15=\"\",\"\",'(3) Export Activity Detail'!O49)","v":""},{"$f":"IF(E15=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U49),\"\",'(3) Export Activity Detail'!U49))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB49),\"\",'(3) Export Activity Detail'!AB49)","v":""},{"$f":"IF(E15=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P49),\"\",LOOKUP('(3) Export Activity Detail'!P49,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E15=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P49),\"\",LOOKUP('(3) Export Activity Detail'!P49,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E16=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E16=\"\",\"\",'(3) Export Activity Detail'!B50)","v":""},{"$f":"IF(E16=\"\",\"\",'(3) Export Activity Detail'!O50)","v":""},{"$f":"IF(E16=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U50),\"\",'(3) Export Activity Detail'!U50))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB50),\"\",'(3) Export Activity Detail'!AB50)","v":""},{"$f":"IF(E16=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P50),\"\",LOOKUP('(3) Export Activity Detail'!P50,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E16=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P50),\"\",LOOKUP('(3) Export Activity Detail'!P50,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E17=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E17=\"\",\"\",'(3) Export Activity Detail'!B51)","v":""},{"$f":"IF(E17=\"\",\"\",'(3) Export Activity Detail'!O51)","v":""},{"$f":"IF(E17=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U51),\"\",'(3) Export Activity Detail'!U51))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB51),\"\",'(3) Export Activity Detail'!AB51)","v":""},{"$f":"IF(E17=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P51),\"\",LOOKUP('(3) Export Activity Detail'!P51,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E17=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P51),\"\",LOOKUP('(3) Export Activity Detail'!P51,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E18=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E18=\"\",\"\",'(3) Export Activity Detail'!B52)","v":""},{"$f":"IF(E18=\"\",\"\",'(3) Export Activity Detail'!O52)","v":""},{"$f":"IF(E18=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U52),\"\",'(3) Export Activity Detail'!U52))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB52),\"\",'(3) Export Activity Detail'!AB52)","v":""},{"$f":"IF(E18=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P52),\"\",LOOKUP('(3) Export Activity Detail'!P52,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E18=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P52),\"\",LOOKUP('(3) Export Activity Detail'!P52,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E19=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E19=\"\",\"\",'(3) Export Activity Detail'!B53)","v":""},{"$f":"IF(E19=\"\",\"\",'(3) Export Activity Detail'!O53)","v":""},{"$f":"IF(E19=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U53),\"\",'(3) Export Activity Detail'!U53))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB53),\"\",'(3) Export Activity Detail'!AB53)","v":""},{"$f":"IF(E19=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P53),\"\",LOOKUP('(3) Export Activity Detail'!P53,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E19=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P53),\"\",LOOKUP('(3) Export Activity Detail'!P53,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E20=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E20=\"\",\"\",'(3) Export Activity Detail'!B54)","v":""},{"$f":"IF(E20=\"\",\"\",'(3) Export Activity Detail'!O54)","v":""},{"$f":"IF(E20=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U54),\"\",'(3) Export Activity Detail'!U54))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB54),\"\",'(3) Export Activity Detail'!AB54)","v":""},{"$f":"IF(E20=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P54),\"\",LOOKUP('(3) Export Activity Detail'!P54,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E20=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P54),\"\",LOOKUP('(3) Export Activity Detail'!P54,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E21=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E21=\"\",\"\",'(3) Export Activity Detail'!B55)","v":""},{"$f":"IF(E21=\"\",\"\",'(3) Export Activity Detail'!O55)","v":""},{"$f":"IF(E21=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U55),\"\",'(3) Export Activity Detail'!U55))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB55),\"\",'(3) Export Activity Detail'!AB55)","v":""},{"$f":"IF(E21=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P55),\"\",LOOKUP('(3) Export Activity Detail'!P55,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E21=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P55),\"\",LOOKUP('(3) Export Activity Detail'!P55,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E22=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E22=\"\",\"\",'(3) Export Activity Detail'!B56)","v":""},{"$f":"IF(E22=\"\",\"\",'(3) Export Activity Detail'!O56)","v":""},{"$f":"IF(E22=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U56),\"\",'(3) Export Activity Detail'!U56))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB56),\"\",'(3) Export Activity Detail'!AB56)","v":""},{"$f":"IF(E22=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P56),\"\",LOOKUP('(3) Export Activity Detail'!P56,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E22=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P56),\"\",LOOKUP('(3) Export Activity Detail'!P56,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E23=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E23=\"\",\"\",'(3) Export Activity Detail'!B57)","v":""},{"$f":"IF(E23=\"\",\"\",'(3) Export Activity Detail'!O57)","v":""},{"$f":"IF(E23=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U57),\"\",'(3) Export Activity Detail'!U57))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB57),\"\",'(3) Export Activity Detail'!AB57)","v":""},{"$f":"IF(E23=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P57),\"\",LOOKUP('(3) Export Activity Detail'!P57,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E23=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P57),\"\",LOOKUP('(3) Export Activity Detail'!P57,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E24=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E24=\"\",\"\",'(3) Export Activity Detail'!B58)","v":""},{"$f":"IF(E24=\"\",\"\",'(3) Export Activity Detail'!O58)","v":""},{"$f":"IF(E24=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U58),\"\",'(3) Export Activity Detail'!U58))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB58),\"\",'(3) Export Activity Detail'!AB58)","v":""},{"$f":"IF(E24=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P58),\"\",LOOKUP('(3) Export Activity Detail'!P58,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E24=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P58),\"\",LOOKUP('(3) Export Activity Detail'!P58,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E25=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E25=\"\",\"\",'(3) Export Activity Detail'!B59)","v":""},{"$f":"IF(E25=\"\",\"\",'(3) Export Activity Detail'!O59)","v":""},{"$f":"IF(E25=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U59),\"\",'(3) Export Activity Detail'!U59))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB59),\"\",'(3) Export Activity Detail'!AB59)","v":""},{"$f":"IF(E25=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P59),\"\",LOOKUP('(3) Export Activity Detail'!P59,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E25=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P59),\"\",LOOKUP('(3) Export Activity Detail'!P59,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E26=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E26=\"\",\"\",'(3) Export Activity Detail'!B60)","v":""},{"$f":"IF(E26=\"\",\"\",'(3) Export Activity Detail'!O60)","v":""},{"$f":"IF(E26=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U60),\"\",'(3) Export Activity Detail'!U60))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB60),\"\",'(3) Export Activity Detail'!AB60)","v":""},{"$f":"IF(E26=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P60),\"\",LOOKUP('(3) Export Activity Detail'!P60,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E26=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P60),\"\",LOOKUP('(3) Export Activity Detail'!P60,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E27=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E27=\"\",\"\",'(3) Export Activity Detail'!B61)","v":""},{"$f":"IF(E27=\"\",\"\",'(3) Export Activity Detail'!O61)","v":""},{"$f":"IF(E27=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U61),\"\",'(3) Export Activity Detail'!U61))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB61),\"\",'(3) Export Activity Detail'!AB61)","v":""},{"$f":"IF(E27=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P61),\"\",LOOKUP('(3) Export Activity Detail'!P61,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E27=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P61),\"\",LOOKUP('(3) Export Activity Detail'!P61,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E28=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E28=\"\",\"\",'(3) Export Activity Detail'!B62)","v":""},{"$f":"IF(E28=\"\",\"\",'(3) Export Activity Detail'!O62)","v":""},{"$f":"IF(E28=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U62),\"\",'(3) Export Activity Detail'!U62))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB62),\"\",'(3) Export Activity Detail'!AB62)","v":""},{"$f":"IF(E28=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P62),\"\",LOOKUP('(3) Export Activity Detail'!P62,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E28=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P62),\"\",LOOKUP('(3) Export Activity Detail'!P62,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E29=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E29=\"\",\"\",'(3) Export Activity Detail'!B63)","v":""},{"$f":"IF(E29=\"\",\"\",'(3) Export Activity Detail'!O63)","v":""},{"$f":"IF(E29=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U63),\"\",'(3) Export Activity Detail'!U63))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB63),\"\",'(3) Export Activity Detail'!AB63)","v":""},{"$f":"IF(E29=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P63),\"\",LOOKUP('(3) Export Activity Detail'!P63,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E29=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P63),\"\",LOOKUP('(3) Export Activity Detail'!P63,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E30=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E30=\"\",\"\",'(3) Export Activity Detail'!B64)","v":""},{"$f":"IF(E30=\"\",\"\",'(3) Export Activity Detail'!O64)","v":""},{"$f":"IF(E30=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U64),\"\",'(3) Export Activity Detail'!U64))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB64),\"\",'(3) Export Activity Detail'!AB64)","v":""},{"$f":"IF(E30=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P64),\"\",LOOKUP('(3) Export Activity Detail'!P64,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E30=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P64),\"\",LOOKUP('(3) Export Activity Detail'!P64,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E31=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E31=\"\",\"\",'(3) Export Activity Detail'!B65)","v":""},{"$f":"IF(E31=\"\",\"\",'(3) Export Activity Detail'!O65)","v":""},{"$f":"IF(E31=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U65),\"\",'(3) Export Activity Detail'!U65))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB65),\"\",'(3) Export Activity Detail'!AB65)","v":""},{"$f":"IF(E31=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P65),\"\",LOOKUP('(3) Export Activity Detail'!P65,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E31=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P65),\"\",LOOKUP('(3) Export Activity Detail'!P65,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E32=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E32=\"\",\"\",'(3) Export Activity Detail'!B66)","v":""},{"$f":"IF(E32=\"\",\"\",'(3) Export Activity Detail'!O66)","v":""},{"$f":"IF(E32=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U66),\"\",'(3) Export Activity Detail'!U66))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB66),\"\",'(3) Export Activity Detail'!AB66)","v":""},{"$f":"IF(E32=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P66),\"\",LOOKUP('(3) Export Activity Detail'!P66,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E32=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P66),\"\",LOOKUP('(3) Export Activity Detail'!P66,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E33=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E33=\"\",\"\",'(3) Export Activity Detail'!B67)","v":""},{"$f":"IF(E33=\"\",\"\",'(3) Export Activity Detail'!O67)","v":""},{"$f":"IF(E33=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U67),\"\",'(3) Export Activity Detail'!U67))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB67),\"\",'(3) Export Activity Detail'!AB67)","v":""},{"$f":"IF(E33=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P67),\"\",LOOKUP('(3) Export Activity Detail'!P67,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E33=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P67),\"\",LOOKUP('(3) Export Activity Detail'!P67,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E34=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E34=\"\",\"\",'(3) Export Activity Detail'!B69)","v":""},{"$f":"IF(E34=\"\",\"\",'(3) Export Activity Detail'!O69)","v":""},{"$f":"IF(E34=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U69),\"\",'(3) Export Activity Detail'!U69))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB69),\"\",'(3) Export Activity Detail'!AB69)","v":""},{"$f":"IF(E34=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P69),\"\",LOOKUP('(3) Export Activity Detail'!P69,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E34=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P69),\"\",LOOKUP('(3) Export Activity Detail'!P69,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E35=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E35=\"\",\"\",'(3) Export Activity Detail'!B71)","v":""},{"$f":"IF(E35=\"\",\"\",'(3) Export Activity Detail'!O71)","v":""},{"$f":"IF(E35=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U71),\"\",'(3) Export Activity Detail'!U71))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB71),\"\",'(3) Export Activity Detail'!AB71)","v":""},{"$f":"IF(E35=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P71),\"\",LOOKUP('(3) Export Activity Detail'!P71,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E35=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P71),\"\",LOOKUP('(3) Export Activity Detail'!P71,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E36=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E36=\"\",\"\",'(3) Export Activity Detail'!B72)","v":""},{"$f":"IF(E36=\"\",\"\",'(3) Export Activity Detail'!O72)","v":""},{"$f":"IF(E36=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U72),\"\",'(3) Export Activity Detail'!U72))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB72),\"\",'(3) Export Activity Detail'!AB72)","v":""},{"$f":"IF(E36=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P72),\"\",LOOKUP('(3) Export Activity Detail'!P72,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E36=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P72),\"\",LOOKUP('(3) Export Activity Detail'!P72,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E37=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E37=\"\",\"\",'(3) Export Activity Detail'!B73)","v":""},{"$f":"IF(E37=\"\",\"\",'(3) Export Activity Detail'!O73)","v":""},{"$f":"IF(E37=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U73),\"\",'(3) Export Activity Detail'!U73))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB73),\"\",'(3) Export Activity Detail'!AB73)","v":""},{"$f":"IF(E37=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P73),\"\",LOOKUP('(3) Export Activity Detail'!P73,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E37=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P73),\"\",LOOKUP('(3) Export Activity Detail'!P73,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E38=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E38=\"\",\"\",'(3) Export Activity Detail'!B74)","v":""},{"$f":"IF(E38=\"\",\"\",'(3) Export Activity Detail'!O74)","v":""},{"$f":"IF(E38=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U74),\"\",'(3) Export Activity Detail'!U74))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB74),\"\",'(3) Export Activity Detail'!AB74)","v":""},{"$f":"IF(E38=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P74),\"\",LOOKUP('(3) Export Activity Detail'!P74,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E38=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P74),\"\",LOOKUP('(3) Export Activity Detail'!P74,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]
[{"$f":"IF(E39=\"\",\"\",'(3) Export Activity Detail'!$J$24)","v":""},{"$f":"IF(E39=\"\",\"\",'(3) Export Activity Detail'!B75)","v":""},{"$f":"IF(E39=\"\",\"\",'(3) Export Activity Detail'!O75)","v":""},{"$f":"IF(E39=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!U75),\"\",'(3) Export Activity Detail'!U75))","v":""},{"$f":"IF(ISBLANK('(3) Export Activity Detail'!AB75),\"\",'(3) Export Activity Detail'!AB75)","v":""},{"$f":"IF(E39=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P75),\"\",LOOKUP('(3) Export Activity Detail'!P75,Facility!$A$79:$A$88,Facility!$C$79:$C$88)))","v":""},{"$f":"IF(E39=\"\",\"\",IF(ISBLANK('(3) Export Activity Detail'!P75),\"\",LOOKUP('(3) Export Activity Detail'!P75,Facility!$A$79:$A$88,Facility!$E$79:$E$88)))","v":""}]